{"id":14974,"date":"2021-08-09T11:12:07","date_gmt":"2021-08-09T09:12:07","guid":{"rendered":"https:\/\/www.vertysystem.com\/equipamento\/artic-pins\/"},"modified":"2024-10-28T11:48:39","modified_gmt":"2024-10-28T10:48:39","slug":"artic-pins","status":"publish","type":"page","link":"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/","title":{"rendered":"Artic Pins"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#efefef&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;testo-header&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;5%&#8221; top_margin_tablet=&#8221;10%&#8221; bottom_margin_tablet=&#8221;60%&#8221; top_margin_phone=&#8221;10%&#8221; bottom_margin_phone=&#8221;60%&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;testo-header&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h3 style=\"text-align: center;\">VERTYS<\/h3>\n<h1 style=\"text-align: center;\">Artic Pins<\/h1>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#efefef&#8221; bg_image=&#8221;5251&#8243; bg_position=&#8221;center bottom&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;sezione-full header&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;5%&#8221; top_margin_tablet=&#8221;10%&#8221; bottom_margin_tablet=&#8221;60%&#8221; top_margin_phone=&#8221;10%&#8221; bottom_margin_phone=&#8221;60%&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#efefef&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-20-percent&#8221; column_padding_tablet=&#8221;padding-5-percent&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; bottom_margin=&#8221;5%&#8221; bottom_margin_tablet=&#8221;5%&#8221; bottom_margin_phone=&#8221;5%&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;descrizione-header&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;testo1&#8243;]\n<p id=\"u1178347-2\" style=\"text-align: center;\"><strong>Um modelo perfeito e sobretudo repet\u00edvel!<\/strong><\/p>\n<p id=\"u1178347-7\" style=\"text-align: center;\">Artic Pins \u00e9 o\u00a0<span id=\"u1178347-5\">sistema para realizar modelos troquelizados<\/span>, precisos e com extrema facilidade!<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#1d1d20&#8243; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;sezione-full perche artic&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div  data-transition=\"fade\" data-overall_style=\"classic\" data-flexible-height=\"\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"\" data-parallax=\"false\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"false\" class=\"nectar-slider-wrap \" id=\"nectar-slider-instance-1\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"true\" data-height=\"650\" data-min-height=\"\" data-arrows=\"true\" data-bullets=\"false\" data-bullet_style=\"see_through\" data-bullet_position=\"bottom\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"bottom\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/08\/slide-artic-pins-1.png);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\">Por que compr\u00e1-lo<\/h2><p  ><span>Porque \u00e9 de extrema comodidade poder replicar um modelo em qualquer momento<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"bottom\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/08\/slide-artic-pins-2.png);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\">Por que compr\u00e1-lo<\/h2><p  ><span>Porque a posi\u00e7\u00e3o \u00e9 sempre precisa e repet\u00edvel<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"bottom\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/08\/slide-artic-pins-3.png);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\">Por que compr\u00e1-lo  <\/h2><p  ><span>Porque h\u00e1 uma correcta rela\u00e7\u00e3o troquel-pino e grande estabilidade do troquel remov\u00edvel<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"bottom\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/08\/slide-artic-pins-4.png);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\">Por que compr\u00e1-lo<\/h2><p  ><span>Porque a placa de tecnopol\u00edmero non se deforma ao longo do tempo<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"bottom\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/08\/slide-artic-pins-6.png);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\">Por que compr\u00e1-lo<\/h2><p  ><span>Porque nos modelos com implantes \u00e9 poss\u00edvel manter uma baixa altura do troquel<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"bottom\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/08\/slide-artic-pins-5.png);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\">Por que compr\u00e1-lo<\/h2><p  ><span>Porque \u00e9 r\u00e1pido e econ\u00f3mico<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><a href=\"#\" aria-label=\"Previous\" class=\"slider-prev\"><i class=\"icon-salient-left-arrow\"><\/i> <div class=\"slide-count\"> <span class=\"slide-current\">1<\/span> <i class=\"icon-salient-right-line\"><\/i> <span class=\"slide-total\"><\/span> <\/div> <\/a>\n\t\t\t\t\t\t<a href=\"#\" aria-label=\"Next\" class=\"slider-next\"><i class=\"icon-salient-right-arrow\"><\/i> <div class=\"slide-count\"> <span class=\"slide-current\">1<\/span> <i class=\"icon-salient-right-line\"><\/i> <span class=\"slide-total\"><\/span> <\/div> <\/a><div class=\"nectar-slider-loading \"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;sezione-full dettagli&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color=&#8221;#efefef&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding_tablet=&#8221;3%&#8221; top_padding_phone=&#8221;3%&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-8-percent&#8221; column_padding_tablet=&#8221;padding-5-percent&#8221; column_padding_phone=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;left-right&#8221; bottom_margin=&#8221;5%&#8221; bottom_margin_tablet=&#8221;3%&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;i-dettagli&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;testo-riga caratteristiche&#8221; css=&#8221;.vc_custom_1637072482265{padding-top: 10% !important;padding-bottom: 10% !important;}&#8221;]\n<h2 class=\"titoletto\" style=\"text-align: left;\">Caracter\u00edsticas:<\/h2>\n<ol>\n<li>Placas de tecnopol\u00edmero de 10 mm de espessura e pinos em lat\u00e3o de 16 mm<\/li>\n<li id=\"u1178297-2\">Grande estabilidade dos troqu\u00e9is<\/li>\n<li id=\"u1178298-2\">Encaixe direto para o Vertysystem<\/li>\n<li>Adapt\u00e1vel a quase todas as perfuradoras de pinos presentes no mercado<\/li>\n<li id=\"u1178300-2\">Reprodutibilidade dos troqu\u00e9is e\/ou dos modelos<\/li>\n<li id=\"u1178301-2\">Possibilidade de baixar consideravelmente a altura do modelo em trabalhos sobre implantes<\/li>\n<\/ol>\n[\/vc_column_text][nectar_video_lightbox link_style=&#8221;nectar-button&#8221; nectar_button_color=&#8221;Default-Accent-Color&#8221; video_url=&#8221;https:\/\/www.youtube.com\/watch?v=wxjiPFW6x2g&#8221; link_text=&#8221;Veja em a\u00e7\u00e3o&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;4472&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; margin_right=&#8221;10%&#8221; el_class=&#8221;imm2&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; bottom_padding_tablet=&#8221;10%&#8221; left_padding_tablet=&#8221;0&#8243; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0&#8243; bottom_padding_phone=&#8221;15%&#8221; left_padding_phone=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;carosello1&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;carosello-assemblaggio&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2 id=\"u1178437-2\" style=\"text-align: center;\">O seu Artic Pins:<\/h2>\n<p style=\"text-align: center;\">Intro Kit<\/p>\n[\/vc_column_text]<div  data-transition=\"fade\" data-overall_style=\"classic\" data-flexible-height=\"\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"\" data-parallax=\"false\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"false\" class=\"nectar-slider-wrap \" id=\"nectar-slider-instance-2\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"true\" data-height=\"900\" data-min-height=\"\" data-arrows=\"true\" data-bullets=\"false\" data-bullet_style=\"see_through\" data-bullet_position=\"bottom\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"top\" data-color-scheme=\"dark\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/08\/Slide-AP-1.jpg);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\"><h2><span style=\"font-weight: normal !important\">200-3100<\/span><\/br>Artic Pins Intro Kit<\/h2><\/h2><p  ><span>Mufla completa para realizar modelos com troqu\u00e9is remov\u00edveis<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"top\" data-color-scheme=\"dark\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/08\/Slide-AP-4.jpg);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\"><h2><span style=\"font-weight: normal !important\">200-3104<\/span><\/br>Artic Pins Cover<\/h2><\/h2><p  ><span>Tampa em alum\u00ednio anodizado dourada<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"top\" data-color-scheme=\"dark\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/08\/Slide-AP-2.jpg);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\"><h2><span style=\"font-weight: normal !important\">200-3102<\/span><\/br>Artic Pins Base<\/h2><\/h2><p  ><span>Base em alum\u00ednio anodizado de cor cinza antracite<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"top\" data-color-scheme=\"dark\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/08\/Slide-AP-3.jpg);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\"><h2><span style=\"font-weight: normal !important\">200-3106<\/span><\/br>Ki Axis Artic Pins<\/h2><\/h2><p  ><span>Varas em a\u00e7o inox graduadas<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"top\" data-color-scheme=\"dark\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/08\/Slide-AP-5.jpg);\"> &nbsp; <\/div><\/div><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\"><h2><span style=\"font-weight: normal !important\">200-3108 | 200-3114 | 200-3115 | 200-3120<\/span><\/br>AP Burs | AP Black Plate | AP Metal Disc | AP Pins<\/h2><\/h2><p  ><span>Acess\u00f3rios para Artic Pins (inclu\u00eddos)<\/span><\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><a href=\"#\" aria-label=\"Previous\" class=\"slider-prev\"><i class=\"icon-salient-left-arrow\"><\/i> <div class=\"slide-count\"> <span class=\"slide-current\">1<\/span> <i class=\"icon-salient-right-line\"><\/i> <span class=\"slide-total\"><\/span> <\/div> <\/a>\n\t\t\t\t\t\t<a href=\"#\" aria-label=\"Next\" class=\"slider-next\"><i class=\"icon-salient-right-arrow\"><\/i> <div class=\"slide-count\"> <span class=\"slide-current\">1<\/span> <i class=\"icon-salient-right-line\"><\/i> <span class=\"slide-total\"><\/span> <\/div> <\/a><div class=\"nectar-slider-loading \"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;riga-tab&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;0.1&#8243; background_image=&#8221;5261&#8243; background_image_position=&#8221;center center&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;tab-inner-column&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;500&#8243; custom_height_tablet=&#8221;400&#8243; custom_height_phone=&#8221;300&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;0.1&#8243; background_image=&#8221;5271&#8243; background_image_position=&#8221;center center&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;tab-inner-column&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;500&#8243; custom_height_tablet=&#8221;400&#8243; custom_height_phone=&#8221;300&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;5281&#8243; background_image_position=&#8221;center center&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;tab-inner-column&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;500&#8243; custom_height_tablet=&#8221;400&#8243; custom_height_phone=&#8221;300&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;sezione-full video&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<style type=\"text\/css\">@media only screen and (min-width: 1300px) { #nectar-slider-instance-3, #nectar-slider-instance-3 .swiper-container { height: 500px; }  } @media only screen and (max-width: 1299px) { #nectar-slider-instance-3, #nectar-slider-instance-3 .swiper-container { height: 416.66666666667px; }  } @media only screen and (max-width: 1000px) { #nectar-slider-instance-3, #nectar-slider-instance-3 .swiper-container { height: 357.14285714286px; }  } @media only screen and (max-width: 690px) { #nectar-slider-instance-3, #nectar-slider-instance-3 .swiper-container { height: 185.18518518519px; }  } <\/style><div  data-transition=\"slide\" data-overall_style=\"classic\" data-flexible-height=\"\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"\" data-parallax=\"false\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"true\" class=\"nectar-slider-wrap \" id=\"nectar-slider-instance-3\"><div class=\"swiper-container\"  data-tho=\"22\" data-tco=\"14\" data-pho=\"22\" data-pco=\"14\" data-loop=\"true\" data-height=\"500\" data-min-height=\"\" data-arrows=\"false\" data-bullets=\"false\" data-bullet_style=\"see_through\" data-bullet_position=\"bottom\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" ><div class=\"container\">\n\t\t\t\t\t\t<div class=\"content\"><h2 class=\"ns-heading-el\">Artic Pins<\/h2><p  ><span>SMART TIPS | Artic Pins Guide<\/span><\/p><div class=\"buttons\"><div class=\"button solid_color\">\n\t\t\t\t\t\t\t\t\t\t <a class=\"pp primary-color\" href=\"https:\/\/www.youtube.com\/watch?v=2yt0F5g_fgM\">AP Guide<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div><\/div><\/div>\n\t\t\t\t\t\t\t\t<\/div><!--\/container--><div class=\"video-texture active_texture\"> <span class=\"ie-fix\"><\/span> <\/div>\n\t\t\t\t\t\t\t\t<div class=\"mobile-video-image\" style=\"background-image: url()\"> <span class=\"ie-fix\"><\/span>  <\/div>\n\t\t\t\t\t\t\t\t<div class=\"slide-bg-wrap\">\n\t\t\t\t\t\t\t\t<div class=\"video-wrap\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<video class=\"slider-video\" width=\"1800\" height=\"700\" preload=\"auto\" loop autoplay muted playsinline><source type=\"video\/webm\" src=\"https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/08\/La-Nostra-Firma-E-La-Nostra-Promessa-1.m4v\"><\/video><\/div> <\/div><\/div> <!--\/swiper-slide--><\/div><div class=\"nectar-slider-loading \"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#efefef&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; left_padding_tablet=&#8221;0&#8243; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;0&#8243; left_padding_phone=&#8221;0&#8243; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;sezione-full brochure&#8221; id=&#8221;contact&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;col-brochure&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2 id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: center;\" data-placeholder=\"Traduzione\"><span class=\"Y2IQFc\" lang=\"pt\">Descreva o material informativo<\/span><\/h2>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: center;\" data-placeholder=\"Traduzione\"><span class=\"Y2IQFc\" lang=\"pt\">Ingrese al \u00e1rea reservada para\u00a0<strong>descargar folletos, protocolos, instrucciones<\/strong>\u00a0y mucho m\u00e1s<\/span><\/p>\n[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; text=&#8221;Area reservada&#8221; url=&#8221;https:\/\/www.vertysystem.com\/pt-pt\/area-reservada\/&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#efefef&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;riga-form&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_margin=&#8221;5%&#8221; constrain_group_3=&#8221;yes&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; el_class=&#8221;colonna-form&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;testo-riga-form&#8221;]\n<h2 style=\"text-align: center;\">Contate para mais informa\u00e7\u00f5es<\/h2>\n[\/vc_column_text]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f13920-o1\" lang=\"pt-PT\" dir=\"ltr\" data-wpcf7-id=\"13920\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt-pt\/wp-json\/wp\/v2\/pages\/14974#wpcf7-f13920-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"13920\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_PT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f13920-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col span_6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Primeiro nome*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col span_6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-surname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Sobrenome\" value=\"\" type=\"text\" name=\"your-surname\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row\">\n\t<div class=\"col span_6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone*\" value=\"\" type=\"tel\" name=\"telefono\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col span_6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-Mail*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"row riga-gdpr\" style=\"display: flex; align-items: center;\">\n\t<div class=\"col span_6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-294\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-294\"><option value=\"Para que voc\u00ea est\u00e1 nos contatando?\">Para que voc\u00ea est\u00e1 nos contatando?<\/option><option value=\"Pre\u00e7o\">Pre\u00e7o<\/option><option value=\"Conselho gr\u00e1tis\">Conselho gr\u00e1tis<\/option><option value=\"De outros\">De outros<\/option><\/select><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col span_6\">\n\t\t<div class=\"col span_2\">\n\t\t\t<div class=\"btn-invia\">\n\t\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Mandar\" \/>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col span_10\">\n\t\t\t<div class=\"campi-gdpr\">\n\t\t\t\t<p class=\"check_privacy\" ><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-742\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-742\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span><br \/>\nEu autorizo <a class=\"informativa-hover\" href=\"#\" target=\"_blank\">o processamento<\/a> de dados pessoais de acordo com a Pol\u00edtica de Privacidade fornecida.\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"categoria\" value=\"\" type=\"hidden\" name=\"categoria\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"lingua\" value=\"\" type=\"hidden\" name=\"lingua\" \/>\n\n<!-- CAMPI UTM -->\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"acDate\" value=\"\" type=\"hidden\" name=\"acDate\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"acSource\" value=\"\" type=\"hidden\" name=\"acSource\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"acMedium\" value=\"\" type=\"hidden\" name=\"acMedium\" \/><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;row-correlati&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;4%&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2 style=\"text-align: center;\">Voc\u00ea tamb\u00e9m pode estar interessado em:<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;20px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;10px&#8221; right_padding_desktop=&#8221;10px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;testo&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin_phone=&#8221;20px&#8221; column_element_spacing=&#8221;default&#8221; background_color=&#8221;#f4f4f4&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; class=&#8221;correlati&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;4362&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;imm-correlati&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;.vc_custom_1651045579635{padding-bottom: 3% !important;}&#8221;]\n<h2 style=\"text-align: center;\">Furbo Plexi<\/h2>\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: center;\" data-placeholder=\"Traduzione\"><span class=\"Y2IQFc\" lang=\"pt\">Verticulador de 3 eixos para moldagem de cer\u00e2mica<\/span><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/muflas\/furbo-plexi\/\">Saiba mais &gt;<\/a><\/strong><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin_phone=&#8221;20px&#8221; column_element_spacing=&#8221;default&#8221; background_color=&#8221;#f4f4f4&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; class=&#8221;correlati&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;4407&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;imm-correlati&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;.vc_custom_1651045620973{padding-bottom: 3% !important;}&#8221;]\n<h2 style=\"text-align: center;\">Vertys Genius<\/h2>\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: center;\" data-placeholder=\"Traduzione\"><span class=\"Y2IQFc\" lang=\"pt\">Resina de poliuretano resistente e precisa<\/span><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.vertysystem.com\/pt-pt\/consumiveis\/resinas\/poliuretano\/\">Saiba mais &gt;<\/a><\/strong><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin_phone=&#8221;20px&#8221; column_element_spacing=&#8221;default&#8221; background_color=&#8221;#f4f4f4&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; class=&#8221;correlati&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;4490&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;imm-correlati&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;.vc_custom_1651045648760{padding-bottom: 3% !important;}&#8221;]\n<h2 style=\"text-align: center;\">Vertys Split Cast<\/h2>\n<p style=\"text-align: center;\">Sistema de desenvolvimento de modelo com engajamento Vertysystem<\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/split-cast\/\">Saiba mais &gt;<\/a><\/strong><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color=&#8221;#f4f4f4&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; class=&#8221;correlati&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;5229&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;imm-correlati&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;.vc_custom_1651045682856{padding-bottom: 3% !important;}&#8221;]\n<h2 style=\"text-align: center;\">Vertys Scan Pink<\/h2>\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: center;\" data-placeholder=\"Traduzione\"><span class=\"Y2IQFc\" lang=\"pt\">Silicone em cartucho para gengiva digitaliz\u00e1vel<\/span><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.vertysystem.com\/pt-pt\/consumiveis\/silicones\/\">Saiba mais &gt;<\/a><\/strong><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#efefef&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;testo-header&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;5%&#8221; top_margin_tablet=&#8221;10%&#8221; bottom_margin_tablet=&#8221;60%&#8221; top_margin_phone=&#8221;10%&#8221; bottom_margin_phone=&#8221;60%&#8221; column_element_spacing=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15975,"parent":13931,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-14974","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desenvolvimento de modelos com pilares remov\u00edveis Artic Pins - Vertysystem<\/title>\n<meta name=\"description\" content=\"Desenvolvimento de modelos com pilares remov\u00edveis. Pode-se utilizar gesso ou resina poliuret\u00e2nica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desenvolvimento de modelos com pilares remov\u00edveis Artic Pins - Vertysystem\" \/>\n<meta property=\"og:description\" content=\"Desenvolvimento de modelos com pilares remov\u00edveis. Pode-se utilizar gesso ou resina poliuret\u00e2nica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/\" \/>\n<meta property=\"og:site_name\" content=\"Vertysystem\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-28T10:48:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/09\/vertys-artic-pins_pi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"594\" \/>\n\t<meta property=\"og:image:height\" content=\"561\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vertysystem.com\\\/pt-pt\\\/equipamento\\\/artic-pins\\\/\",\"url\":\"https:\\\/\\\/www.vertysystem.com\\\/pt-pt\\\/equipamento\\\/artic-pins\\\/\",\"name\":\"Desenvolvimento de modelos com pilares remov\u00edveis Artic Pins - Vertysystem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vertysystem.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vertysystem.com\\\/pt-pt\\\/equipamento\\\/artic-pins\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vertysystem.com\\\/pt-pt\\\/equipamento\\\/artic-pins\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vertysystem.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/vertys-artic-pins_pi.png\",\"datePublished\":\"2021-08-09T09:12:07+00:00\",\"dateModified\":\"2024-10-28T10:48:39+00:00\",\"description\":\"Desenvolvimento de modelos com pilares remov\u00edveis. Pode-se utilizar gesso ou resina poliuret\u00e2nica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vertysystem.com\\\/pt-pt\\\/equipamento\\\/artic-pins\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vertysystem.com\\\/pt-pt\\\/equipamento\\\/artic-pins\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.vertysystem.com\\\/pt-pt\\\/equipamento\\\/artic-pins\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vertysystem.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/vertys-artic-pins_pi.png\",\"contentUrl\":\"https:\\\/\\\/www.vertysystem.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/vertys-artic-pins_pi.png\",\"width\":594,\"height\":561},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vertysystem.com\\\/pt-pt\\\/equipamento\\\/artic-pins\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vertysystem.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equipamento\",\"item\":\"https:\\\/\\\/www.vertysystem.com\\\/pt-pt\\\/equipamento\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Artic Pins\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vertysystem.com\\\/#website\",\"url\":\"https:\\\/\\\/www.vertysystem.com\\\/\",\"name\":\"Vertysystem\",\"description\":\"Il Sistema pensato per gli Odontotecnici | Vertysystem\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vertysystem.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desenvolvimento de modelos com pilares remov\u00edveis Artic Pins - Vertysystem","description":"Desenvolvimento de modelos com pilares remov\u00edveis. Pode-se utilizar gesso ou resina poliuret\u00e2nica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/","og_locale":"pt_PT","og_type":"article","og_title":"Desenvolvimento de modelos com pilares remov\u00edveis Artic Pins - Vertysystem","og_description":"Desenvolvimento de modelos com pilares remov\u00edveis. Pode-se utilizar gesso ou resina poliuret\u00e2nica.","og_url":"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/","og_site_name":"Vertysystem","article_modified_time":"2024-10-28T10:48:39+00:00","og_image":[{"width":594,"height":561,"url":"https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/09\/vertys-artic-pins_pi.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/","url":"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/","name":"Desenvolvimento de modelos com pilares remov\u00edveis Artic Pins - Vertysystem","isPartOf":{"@id":"https:\/\/www.vertysystem.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/#primaryimage"},"image":{"@id":"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/09\/vertys-artic-pins_pi.png","datePublished":"2021-08-09T09:12:07+00:00","dateModified":"2024-10-28T10:48:39+00:00","description":"Desenvolvimento de modelos com pilares remov\u00edveis. Pode-se utilizar gesso ou resina poliuret\u00e2nica.","breadcrumb":{"@id":"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/#primaryimage","url":"https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/09\/vertys-artic-pins_pi.png","contentUrl":"https:\/\/www.vertysystem.com\/wp-content\/uploads\/2021\/09\/vertys-artic-pins_pi.png","width":594,"height":561},{"@type":"BreadcrumbList","@id":"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/artic-pins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vertysystem.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Equipamento","item":"https:\/\/www.vertysystem.com\/pt-pt\/equipamento\/"},{"@type":"ListItem","position":3,"name":"Artic Pins"}]},{"@type":"WebSite","@id":"https:\/\/www.vertysystem.com\/#website","url":"https:\/\/www.vertysystem.com\/","name":"Vertysystem","description":"Il Sistema pensato per gli Odontotecnici | Vertysystem","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vertysystem.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/www.vertysystem.com\/pt-pt\/wp-json\/wp\/v2\/pages\/14974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vertysystem.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vertysystem.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vertysystem.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vertysystem.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=14974"}],"version-history":[{"count":8,"href":"https:\/\/www.vertysystem.com\/pt-pt\/wp-json\/wp\/v2\/pages\/14974\/revisions"}],"predecessor-version":[{"id":24113,"href":"https:\/\/www.vertysystem.com\/pt-pt\/wp-json\/wp\/v2\/pages\/14974\/revisions\/24113"}],"up":[{"embeddable":true,"href":"https:\/\/www.vertysystem.com\/pt-pt\/wp-json\/wp\/v2\/pages\/13931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vertysystem.com\/pt-pt\/wp-json\/wp\/v2\/media\/15975"}],"wp:attachment":[{"href":"https:\/\/www.vertysystem.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=14974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}